{"id":33046,"date":"2025-03-05T02:27:43","date_gmt":"2025-03-05T02:27:43","guid":{"rendered":"https:\/\/casinojesus.com\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/"},"modified":"2025-03-05T02:27:43","modified_gmt":"2025-03-05T02:27:43","slug":"andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720","status":"publish","type":"post","link":"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/","title":{"rendered":"\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720!"},"content":{"rendered":"<p><html><body><\/p>\n<h1>\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720!<\/h1>\n<p>\u00a1Ag\u00e1rrense que les cuento! El Grosvenor UK Open Main Event 2025, un tornazo con buy-in de \u00a31,500 celebrado en Coventry, \u00a1explot\u00f3 todas las expectativas! Con 951 participantes (incluyendo 240 re-entradas), el pozo de premios alcanz\u00f3 la friolera de \u00a31,219,660, \u00a1superando el mill\u00f3n garantizado! El premio gordo: unos jugosos \u00a3219,720.<\/p>\n<p>Andrew \u00abStato_1\u00bb Hulme, \u00a1tremendo crack!, se llev\u00f3 la gloria y escribi\u00f3 su nombre con letras de oro. Este maestro brit\u00e1nico de las cartas ya acumula millones en ganancias online y otros $3.7 millones en torneos presenciales, incluyendo un subcampeonato en el EPT Barcelona Main Event 2024 por \u20ac1,165,614.<\/p>\n<p>Esta victoria es a\u00fan m\u00e1s dulce porque marca su segundo premio de seis cifras en territorio brit\u00e1nico, despu\u00e9s de haber conquistado el GUKPT London Main Event 2018 por \u00a3112,400. \u00a1Como dicen por ac\u00e1, en casa y con la copa!<\/p>\n<p>As\u00ed qued\u00f3 la mesa final, \u00a1puro nivel!:<br \/>\n1. Andrew Hulme &#8211; \u00a3219,720<br \/>\n2. Raymond Power &#8211; \u00a3160,390<br \/>\n3. Dale Wilson &#8211; \u00a3116,840<br \/>\n4. Antoine Labat &#8211; \u00a384,890<br \/>\n5. Martin Donoghue &#8211; \u00a361,230<br \/>\n6. James Clarke &#8211; \u00a343,910<br \/>\n7. Tuan Van Le &#8211; \u00a331,340<br \/>\n8. Wantao Tang &#8211; \u00a322,440<br \/>\n9. Iason Filippidis &#8211; \u00a316,350<\/p>\n<p>Entre los 121 jugadores que cobraron premio, brillaron figuras como Paul Vas Nunes, Mitchell Johnson, John Bousfield, Richard Ashby, Dean Hutchison, Antoine Saout, Keith Johnson, Vanessa Kade, Yucel \u00abMad Turk\u00bb Eminoglu y Matthew Davenport.<\/p>\n<p>En otros eventos del festival, Rhys Keen se coron\u00f3 en el High Roller llev\u00e1ndose \u00a372,000, Phil Tate domin\u00f3 el Mini Main de \u00a3340 por \u00a345,000, y Andrew Hawksby se alz\u00f3 con el GUKPT Cup de \u00a3550 embols\u00e1ndose \u00a327,690.<\/p>\n<p>\u00a1Pero esto no termina aqu\u00ed! El GUKPT regresa con todo en Luton del 24 de abril al 2 de mayo 2025, con un Main Event de \u00a31,250 y \u00a1\u00a3250,000 garantizados! \u00a1No se lo pierdan!<\/p>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720! \u00a1Ag\u00e1rrense que les cuento! El Grosvenor UK Open Main Event 2025, un tornazo con buy-in de \u00a31,500 celebrado en Coventry, \u00a1explot\u00f3 todas las expectativas! Con 951 participantes (incluyendo 240 re-entradas), el pozo de premios alcanz\u00f3 la friolera de \u00a31,219,660, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33026,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[290],"tags":[],"class_list":{"0":"post-33046","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-poker-es"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720! - Casino Jesus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-\u00a3219720\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720! - Casino Jesus\" \/>\n<meta property=\"og:description\" content=\"\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720! \u00a1Ag\u00e1rrense que les cuento! El Grosvenor UK Open Main Event 2025, un tornazo con buy-in de \u00a31,500 celebrado en Coventry, \u00a1explot\u00f3 todas las expectativas! Con 951 participantes (incluyendo 240 re-entradas), el pozo de premios alcanz\u00f3 la friolera de \u00a31,219,660, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-\u00a3219720\/\" \/>\n<meta property=\"og:site_name\" content=\"Casino Jesus\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-05T02:27:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casinojesus.com\/wp-content\/uploads\/2025\/03\/Andrew-Hulme-Wins-the-Massive-2025-Grosvenor-UK-Open-for-219-720-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"The Casino Jesus Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"The Casino Jesus Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/\"},\"author\":{\"name\":\"The Casino Jesus Team\",\"@id\":\"https:\/\/casinojesus.com\/#\/schema\/person\/ac55f245598e514e71d25fe9b0d66a21\"},\"headline\":\"\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720!\",\"datePublished\":\"2025-03-05T02:27:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/\"},\"wordCount\":296,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/casinojesus.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casinojesus.com\/wp-content\/uploads\/2025\/03\/Andrew-Hulme-Wins-the-Massive-2025-Grosvenor-UK-Open-for-219-720-3.png\",\"articleSection\":[\"Poker\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/\",\"url\":\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/\",\"name\":\"\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720! - Casino Jesus\",\"isPartOf\":{\"@id\":\"https:\/\/casinojesus.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casinojesus.com\/wp-content\/uploads\/2025\/03\/Andrew-Hulme-Wins-the-Massive-2025-Grosvenor-UK-Open-for-219-720-3.png\",\"datePublished\":\"2025-03-05T02:27:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#primaryimage\",\"url\":\"https:\/\/casinojesus.com\/wp-content\/uploads\/2025\/03\/Andrew-Hulme-Wins-the-Massive-2025-Grosvenor-UK-Open-for-219-720-3.png\",\"contentUrl\":\"https:\/\/casinojesus.com\/wp-content\/uploads\/2025\/03\/Andrew-Hulme-Wins-the-Massive-2025-Grosvenor-UK-Open-for-219-720-3.png\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/casinojesus.com\/es\/inicio-nuevo-diseno\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casinojesus.com\/#website\",\"url\":\"https:\/\/casinojesus.com\/\",\"name\":\"Casino Jesus\",\"description\":\"Blessed with the Best Casino Reviews Online\",\"publisher\":{\"@id\":\"https:\/\/casinojesus.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casinojesus.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casinojesus.com\/#organization\",\"name\":\"Casino Jesus\",\"url\":\"https:\/\/casinojesus.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/casinojesus.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casinojesus.com\/wp-content\/uploads\/2025\/01\/Group-17-1.png\",\"contentUrl\":\"https:\/\/casinojesus.com\/wp-content\/uploads\/2025\/01\/Group-17-1.png\",\"width\":288,\"height\":94,\"caption\":\"Casino Jesus\"},\"image\":{\"@id\":\"https:\/\/casinojesus.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casinojesus.com\/#\/schema\/person\/ac55f245598e514e71d25fe9b0d66a21\",\"name\":\"The Casino Jesus Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/casinojesus.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2245f59b10d8fd241b1d4f787fe3505b1f91061dcd957edd295367f4e645f48a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2245f59b10d8fd241b1d4f787fe3505b1f91061dcd957edd295367f4e645f48a?s=96&d=mm&r=g\",\"caption\":\"The Casino Jesus Team\"},\"sameAs\":[\"https:\/\/casinojesus.com\"],\"url\":\"https:\/\/casinojesus.com\/es\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720! - Casino Jesus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-\u00a3219720\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720! - Casino Jesus","og_description":"\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720! \u00a1Ag\u00e1rrense que les cuento! El Grosvenor UK Open Main Event 2025, un tornazo con buy-in de \u00a31,500 celebrado en Coventry, \u00a1explot\u00f3 todas las expectativas! Con 951 participantes (incluyendo 240 re-entradas), el pozo de premios alcanz\u00f3 la friolera de \u00a31,219,660, [&hellip;]","og_url":"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-\u00a3219720\/","og_site_name":"Casino Jesus","article_published_time":"2025-03-05T02:27:43+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/casinojesus.com\/wp-content\/uploads\/2025\/03\/Andrew-Hulme-Wins-the-Massive-2025-Grosvenor-UK-Open-for-219-720-3.png","type":"image\/png"}],"author":"The Casino Jesus Team","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"The Casino Jesus Team","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#article","isPartOf":{"@id":"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/"},"author":{"name":"The Casino Jesus Team","@id":"https:\/\/casinojesus.com\/#\/schema\/person\/ac55f245598e514e71d25fe9b0d66a21"},"headline":"\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720!","datePublished":"2025-03-05T02:27:43+00:00","mainEntityOfPage":{"@id":"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/"},"wordCount":296,"commentCount":0,"publisher":{"@id":"https:\/\/casinojesus.com\/#organization"},"image":{"@id":"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#primaryimage"},"thumbnailUrl":"https:\/\/casinojesus.com\/wp-content\/uploads\/2025\/03\/Andrew-Hulme-Wins-the-Massive-2025-Grosvenor-UK-Open-for-219-720-3.png","articleSection":["Poker"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/","url":"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/","name":"\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720! - Casino Jesus","isPartOf":{"@id":"https:\/\/casinojesus.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#primaryimage"},"image":{"@id":"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#primaryimage"},"thumbnailUrl":"https:\/\/casinojesus.com\/wp-content\/uploads\/2025\/03\/Andrew-Hulme-Wins-the-Massive-2025-Grosvenor-UK-Open-for-219-720-3.png","datePublished":"2025-03-05T02:27:43+00:00","breadcrumb":{"@id":"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#primaryimage","url":"https:\/\/casinojesus.com\/wp-content\/uploads\/2025\/03\/Andrew-Hulme-Wins-the-Massive-2025-Grosvenor-UK-Open-for-219-720-3.png","contentUrl":"https:\/\/casinojesus.com\/wp-content\/uploads\/2025\/03\/Andrew-Hulme-Wins-the-Massive-2025-Grosvenor-UK-Open-for-219-720-3.png","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/casinojesus.com\/es\/andrew-hulme-se-corona-campeon-del-super-torneo-grosvenor-uk-open-2025-y-se-lleva-%c2%a3219720\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casinojesus.com\/es\/inicio-nuevo-diseno\/"},{"@type":"ListItem","position":2,"name":"\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720!"}]},{"@type":"WebSite","@id":"https:\/\/casinojesus.com\/#website","url":"https:\/\/casinojesus.com\/","name":"Casino Jesus","description":"Blessed with the Best Casino Reviews Online","publisher":{"@id":"https:\/\/casinojesus.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casinojesus.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casinojesus.com\/#organization","name":"Casino Jesus","url":"https:\/\/casinojesus.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casinojesus.com\/#\/schema\/logo\/image\/","url":"https:\/\/casinojesus.com\/wp-content\/uploads\/2025\/01\/Group-17-1.png","contentUrl":"https:\/\/casinojesus.com\/wp-content\/uploads\/2025\/01\/Group-17-1.png","width":288,"height":94,"caption":"Casino Jesus"},"image":{"@id":"https:\/\/casinojesus.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casinojesus.com\/#\/schema\/person\/ac55f245598e514e71d25fe9b0d66a21","name":"The Casino Jesus Team","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casinojesus.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2245f59b10d8fd241b1d4f787fe3505b1f91061dcd957edd295367f4e645f48a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2245f59b10d8fd241b1d4f787fe3505b1f91061dcd957edd295367f4e645f48a?s=96&d=mm&r=g","caption":"The Casino Jesus Team"},"sameAs":["https:\/\/casinojesus.com"],"url":"https:\/\/casinojesus.com\/es\/author\/admin\/"}]}},"trid":"27808","translations":{"en":{"translation_id":"32881","language_code":"en","element_id":"32607","source_language_code":null,"element_type":"post_post","original":"1","post_title":"Andrew Hulme Wins the Massive 2025 Grosvenor UK Open for \u00a3219,720","post_status":"publish"},"es":{"translation_id":"33320","language_code":"es","element_id":"33046","source_language_code":"en","element_type":"post_post","original":"0","post_title":"\u00a1Andrew Hulme se Corona Campe\u00f3n del S\u00faper Torneo Grosvenor UK Open 2025 y Se Lleva \u00a3219,720!","post_status":"publish"},"fr":{"translation_id":"33739","language_code":"fr","element_id":"33465","source_language_code":"en","element_type":"post_post","original":"0","post_title":"Andr\u00e9 Hulme Rafle la Mise au Gros Tournoi UK Open 2025 : 219 720 Livres Sterling dans la Poche !","post_status":"publish"},"pt-br":{"translation_id":"34157","language_code":"pt-br","element_id":"33883","source_language_code":"en","element_type":"post_post","original":"0","post_title":"Andrew Hulme Conquista o Gigantesco Grosvenor UK Open 2025 e Fatura \u00a3219.720","post_status":"publish"},"uk":{"translation_id":"34651","language_code":"uk","element_id":"34377","source_language_code":"en","element_type":"post_post","original":"0","post_title":"\u0415\u043d\u0434\u0440\u044e \u0425\u0443\u043b\u044c\u043c \u0432\u0438\u0433\u0440\u0430\u0454 \u0433\u0440\u0430\u043d\u0434\u0456\u043e\u0437\u043d\u0438\u0439 \u0413\u0440\u043e\u0441\u0432\u0435\u043d\u043e\u0440 UK Open 2025 \u0440\u043e\u043a\u0443 \u0442\u0430 \u043e\u0442\u0440\u0438\u043c\u0443\u0454 \u00a3219,720","post_status":"publish"},"pl":{"translation_id":"35089","language_code":"pl","element_id":"34815","source_language_code":"en","element_type":"post_post","original":"0","post_title":"Andrew Hulme Zgarnia Gigantyczn\u0105 Wygran\u0105 \u00a3219,720 w Turnieju Grosvenor UK Open 2025!","post_status":"publish"},"fi":{"translation_id":"35925","language_code":"fi","element_id":"35651","source_language_code":"en","element_type":"post_post","original":"0","post_title":"Andrew Hulme nappasi huikean 2025 Grosvenor UK Openin voiton - potti 219 720 puntaa!","post_status":"publish"},"nl":{"translation_id":"36363","language_code":"nl","element_id":"36089","source_language_code":"en","element_type":"post_post","original":"0","post_title":"Andrew Hulme Pakt Gigantische Overwinning van \u00a3219.720 bij 2025 Grosvenor UK Open","post_status":"publish"},"zh-hans":{"translation_id":"39026","language_code":"zh-hans","element_id":"38753","source_language_code":"en","element_type":"post_post","original":"0","post_title":"\u724c\u738bAndrew Hulme\u6a2a\u626b2025\u82f1\u56fd\u683c\u7f57\u592b\u7eb3\u516c\u5f00\u8d5b\uff0c\u8c6a\u63fd21.9\u4e07\u82f1\u9551\u5927\u5956\uff01","post_status":"publish"},"ja":{"translation_id":"40311","language_code":"ja","element_id":"40038","source_language_code":"en","element_type":"post_post","original":"0","post_title":"\u30cf\u30eb\u30e0\u9078\u624b\u30012025\u5e74\u30b0\u30ed\u30d6\u30ca\u30fcUK\u30aa\u30fc\u30d7\u30f3\u3067\u5927\u52dd\u5229\uff01\u8cde\u91d12\u51049\u5343\u4e07\u5186\u3092\u7372\u5f97","post_status":"publish"},"id":{"translation_id":"40853","language_code":"id","element_id":"40580","source_language_code":"en","element_type":"post_post","original":"0","post_title":"Andrew Hulme Raih Kemenangan Besar di Grosvenor UK Open 2025, Bawa Pulang \u00a3219,720!","post_status":"publish"},"et":{"translation_id":"41375","language_code":"et","element_id":"41102","source_language_code":"en","element_type":"post_post","original":"0","post_title":"Andrew Hulme v\u00f5itis 2025. aasta Grosvenori UK lahtised meistriv\u00f5istlused ja teenis 219 720 naela","post_status":"publish"},"lv":{"translation_id":"43397","language_code":"lv","element_id":"43124","source_language_code":"en","element_type":"post_post","original":"0","post_title":"Endrj\u016b Hulme triumf\u0113 2025. gada Grosvenor UK Open turn\u012br\u0101, izc\u012bnot \u00a3219,720","post_status":"publish"},"ar":{"translation_id":"46799","language_code":"ar","element_id":"46526","source_language_code":"en","element_type":"post_post","original":"0","post_title":"\u0645\u0641\u0627\u062c\u0623\u0629 \u0643\u0628\u064a\u0631\u0629: \u0623\u0646\u062f\u0631\u0648 \u0647\u0648\u0644\u0645 \u064a\u0641\u0648\u0632 \u0628\u0628\u0637\u0648\u0644\u0629 \u063a\u0631\u0648\u0633\u0641\u064a\u0646\u0648\u0631 \u0627\u0644\u0645\u0641\u062a\u0648\u062d\u0629 \u0662\u0660\u0662\u0665 \u0648\u064a\u062d\u0635\u062f \u0662\u0661\u0669,\u0667\u0662\u0660 \u062c\u0646\u064a\u0647 \u0625\u0633\u062a\u0631\u0644\u064a\u0646\u064a!","post_status":"publish"},"ru":{"translation_id":"47361","language_code":"ru","element_id":"47088","source_language_code":"en","element_type":"post_post","original":"0","post_title":"\u042d\u043d\u0434\u0440\u044e \u0425\u0430\u043b\u043c \u0432\u044b\u0438\u0433\u0440\u044b\u0432\u0430\u0435\u0442 \u0433\u0440\u0430\u043d\u0434\u0438\u043e\u0437\u043d\u044b\u0439 Grosvenor UK Open 2025 \u0438 \u0437\u0430\u0431\u0438\u0440\u0430\u0435\u0442 \u00a3219,720","post_status":"publish"},"hu":{"translation_id":"60485","language_code":"hu","element_id":"60213","source_language_code":"en","element_type":"post_post","original":"0","post_title":"Keith Heine zapisuje si\u0119 z\u0142otymi zg\u0142oskami w historii MSPT, \u015bwietny wyst\u0119p Grega Raymera w St. Louis","post_status":"publish"},"vi":{"translation_id":"62740","language_code":"vi","element_id":"62468","source_language_code":"en","element_type":"post_post","original":"0","post_title":"Keith Heine Poker D\u00fcnyas\u0131nda \u0130z B\u0131rak\u0131yor, Greg Raymer St. Louis'de Ba\u015far\u0131l\u0131 Bir Performans Sergiliyor","post_status":"publish"}},"language":{"language_code":"es","locale":"es_ES","text_direction":false,"display_name":"Espa\u00f1ol","native_name":"Spanish","different_language":false},"default_language":"en","translation_status":true,"translation_info":[],"_links":{"self":[{"href":"https:\/\/casinojesus.com\/es\/wp-json\/wp\/v2\/posts\/33046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casinojesus.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casinojesus.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casinojesus.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/casinojesus.com\/es\/wp-json\/wp\/v2\/comments?post=33046"}],"version-history":[{"count":0,"href":"https:\/\/casinojesus.com\/es\/wp-json\/wp\/v2\/posts\/33046\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casinojesus.com\/es\/wp-json\/wp\/v2\/media\/33026"}],"wp:attachment":[{"href":"https:\/\/casinojesus.com\/es\/wp-json\/wp\/v2\/media?parent=33046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casinojesus.com\/es\/wp-json\/wp\/v2\/categories?post=33046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casinojesus.com\/es\/wp-json\/wp\/v2\/tags?post=33046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}